{"id":878301,"date":"2025-12-30T14:34:47","date_gmt":"2025-12-30T14:34:47","guid":{"rendered":"https:\/\/pandanetwork.club\/empirescenes\/2025\/12\/30\/girl-girl-studio-8\/"},"modified":"2025-12-30T14:34:47","modified_gmt":"2025-12-30T14:34:47","slug":"girl-girl-studio-8","status":"publish","type":"post","link":"https:\/\/pandanetwork.club\/empirescenes\/2025\/12\/30\/girl-girl-studio-8\/","title":{"rendered":"Girl Girl Studio 8"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2335],"tags":[],"movieactors":[15378,21444,7549,33289,15609,34291,33843,34285,31556],"moviegenres":[2533,2340,2341,2343,2344,2534,2514,2345,2346],"moviestudios":[2336],"movieyears":[5039],"class_list":["post-878301","post","type-post","status-publish","format-standard","hentry","category-adultempire-all-movies","movieactors-hana-black","movieactors-jana-x","movieactors-judith-eufrat","movieactors-keana-moire","movieactors-mila-dark","movieactors-moire-candy","movieactors-sandra-sanchez","movieactors-wildy","movieactors-zuzana-z","moviegenres-cunnilingus","moviegenres-ethnic","moviegenres-european","moviegenres-feature","moviegenres-international","moviegenres-lesbian","moviegenres-oral","moviegenres-plot-oriented","moviegenres-popular-with-women","moviestudios-private","movieyears-5039"],"acf":[],"_links":{"self":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/878301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/comments?post=878301"}],"version-history":[{"count":0,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/878301\/revisions"}],"wp:attachment":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/media?parent=878301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/categories?post=878301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/tags?post=878301"},{"taxonomy":"movieactors","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieactors?post=878301"},{"taxonomy":"moviegenres","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviegenres?post=878301"},{"taxonomy":"moviestudios","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviestudios?post=878301"},{"taxonomy":"movieyears","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieyears?post=878301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}