{"id":863439,"date":"2025-12-29T12:25:51","date_gmt":"2025-12-29T12:25:51","guid":{"rendered":"https:\/\/pandanetwork.club\/empirescenes\/2025\/12\/29\/the-hacienda\/"},"modified":"2025-12-29T12:25:51","modified_gmt":"2025-12-29T12:25:51","slug":"the-hacienda","status":"publish","type":"post","link":"https:\/\/pandanetwork.club\/empirescenes\/2025\/12\/29\/the-hacienda\/","title":{"rendered":"The Hacienda"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2335],"tags":[],"movieactors":[8159,2446,25881,3087,11134,5697,6044,11537,16433,17259,12708,5841,6962,34452,2578,17420],"moviegenres":[2388,3331,2340,2341,2343,2497,2344,2645,2345,2346],"moviestudios":[13854],"movieyears":[2806],"class_list":["post-863439","post","type-post","status-publish","format-standard","hentry","category-adultempire-all-movies","movieactors-dora-venter","movieactors-eva-angelina","movieactors-james-matarazo","movieactors-lauro-giotto","movieactors-lee-henshaw","movieactors-marco","movieactors-marco-banderas","movieactors-oliver-sanchez","movieactors-olivier","movieactors-poppy-morgan","movieactors-priva-rey","movieactors-simony-diamond","movieactors-stacy-silver","movieactors-steven-angelo","movieactors-tony-desergio","movieactors-zoltan","moviegenres-anal","moviegenres-british","moviegenres-ethnic","moviegenres-european","moviegenres-feature","moviegenres-group-sex","moviegenres-international","moviegenres-orgy","moviegenres-plot-oriented","moviegenres-popular-with-women","moviestudios-harmony-films","movieyears-2806"],"acf":[],"_links":{"self":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/863439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/comments?post=863439"}],"version-history":[{"count":0,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/863439\/revisions"}],"wp:attachment":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/media?parent=863439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/categories?post=863439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/tags?post=863439"},{"taxonomy":"movieactors","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieactors?post=863439"},{"taxonomy":"moviegenres","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviegenres?post=863439"},{"taxonomy":"moviestudios","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviestudios?post=863439"},{"taxonomy":"movieyears","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieyears?post=863439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}