{"id":853330,"date":"2025-12-29T09:24:13","date_gmt":"2025-12-29T09:24:13","guid":{"rendered":"https:\/\/pandanetwork.club\/empirescenes\/2025\/12\/29\/come-on-and-touch-me\/"},"modified":"2025-12-29T09:24:13","modified_gmt":"2025-12-29T09:24:13","slug":"come-on-and-touch-me","status":"publish","type":"post","link":"https:\/\/pandanetwork.club\/empirescenes\/2025\/12\/29\/come-on-and-touch-me\/","title":{"rendered":"Come On and Touch Me"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2335],"tags":[],"movieactors":[7426,9534,2362,6805,25621,16118,17550,5285,29041,14839,7423,29137,29495,7431,25179],"moviegenres":[2495,2723,2349],"moviestudios":[29037],"movieyears":[5290],"class_list":["post-853330","post","type-post","status-publish","format-standard","hentry","category-adultempire-all-movies","movieactors-anthony-hardwood","movieactors-barrett-blade","movieactors-cheyne-collins","movieactors-damien-steele","movieactors-dic-tracy","movieactors-lea-de-mae","movieactors-mike-hawk","movieactors-pason","movieactors-rick-davis","movieactors-samantha-slater","movieactors-sativa-rose","movieactors-selena-silver","movieactors-stephanie-tripp","movieactors-tyce-bune","movieactors-tyler-wood","moviegenres-cumshots","moviegenres-facials","moviegenres-gonzo","moviestudios-cherry-boxxx-pictures","movieyears-5290"],"acf":[],"_links":{"self":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/853330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/comments?post=853330"}],"version-history":[{"count":0,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/853330\/revisions"}],"wp:attachment":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/media?parent=853330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/categories?post=853330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/tags?post=853330"},{"taxonomy":"movieactors","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieactors?post=853330"},{"taxonomy":"moviegenres","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviegenres?post=853330"},{"taxonomy":"moviestudios","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviestudios?post=853330"},{"taxonomy":"movieyears","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieyears?post=853330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}