{"id":1016193,"date":"2026-01-09T11:32:15","date_gmt":"2026-01-09T11:32:15","guid":{"rendered":"https:\/\/pandanetwork.club\/empirescenes\/2026\/01\/09\/sex-hostel-1-fucking-venezuelan-in-the-kitchen\/"},"modified":"2026-01-09T11:32:15","modified_gmt":"2026-01-09T11:32:15","slug":"sex-hostel-1-fucking-venezuelan-in-the-kitchen","status":"publish","type":"post","link":"https:\/\/pandanetwork.club\/empirescenes\/2026\/01\/09\/sex-hostel-1-fucking-venezuelan-in-the-kitchen\/","title":{"rendered":"Sex Hostel 1 &#8211; Fucking venezuelan in the kitchen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2335],"tags":[],"movieactors":[3257,8836,9010],"moviegenres":[2389,2552,2424,2763,2340,2341,2344,2415,2886,2421,3664,2422,2348,2392,3239],"moviestudios":[3254],"movieyears":[2827],"class_list":["post-1016193","post","type-post","status-publish","format-standard","hentry","category-adultempire-all-movies","movieactors-capitano-eric","movieactors-kesha-ortega","movieactors-luca-borromeo","moviegenres-appearance","moviegenres-big-butt","moviegenres-big-tits","moviegenres-brunettes","moviegenres-ethnic","moviegenres-european","moviegenres-international","moviegenres-interracial","moviegenres-interracial-caucasian-men","moviegenres-interracial-latin-girls","moviegenres-kitchen","moviegenres-latin","moviegenres-settings","moviegenres-shaved","moviegenres-voluptuous","moviestudios-spicylab","movieyears-2827"],"acf":[],"_links":{"self":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/1016193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/comments?post=1016193"}],"version-history":[{"count":0,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/1016193\/revisions"}],"wp:attachment":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/media?parent=1016193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/categories?post=1016193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/tags?post=1016193"},{"taxonomy":"movieactors","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieactors?post=1016193"},{"taxonomy":"moviegenres","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviegenres?post=1016193"},{"taxonomy":"moviestudios","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviestudios?post=1016193"},{"taxonomy":"movieyears","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieyears?post=1016193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}