{"id":1016170,"date":"2026-01-09T11:31:45","date_gmt":"2026-01-09T11:31:45","guid":{"rendered":"https:\/\/pandanetwork.club\/empirescenes\/2026\/01\/09\/asian-amazement-2\/"},"modified":"2026-01-09T11:31:45","modified_gmt":"2026-01-09T11:31:45","slug":"asian-amazement-2","status":"publish","type":"post","link":"https:\/\/pandanetwork.club\/empirescenes\/2026\/01\/09\/asian-amazement-2\/","title":{"rendered":"Asian Amazement 2"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2335],"tags":[],"movieactors":[9801,2612,2366,4559,4560,2467,7288,16380],"moviegenres":[2999,2340,2344,2415,3000,2886],"moviestudios":[11671],"movieyears":[2827],"class_list":["post-1016170","post","type-post","status-publish","format-standard","hentry","category-adultempire-all-movies","movieactors-ariel-rose","movieactors-denis-marti","movieactors-john-west","movieactors-kya-tropic","movieactors-lana-violet","movieactors-mr-pete","movieactors-vicki-chase","movieactors-war-machine","moviegenres-asian","moviegenres-ethnic","moviegenres-international","moviegenres-interracial","moviegenres-interracial-asian-girls","moviegenres-interracial-caucasian-men","moviestudios-aura-productions","movieyears-2827"],"acf":[],"_links":{"self":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/1016170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/comments?post=1016170"}],"version-history":[{"count":0,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/1016170\/revisions"}],"wp:attachment":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/media?parent=1016170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/categories?post=1016170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/tags?post=1016170"},{"taxonomy":"movieactors","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieactors?post=1016170"},{"taxonomy":"moviegenres","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviegenres?post=1016170"},{"taxonomy":"moviestudios","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviestudios?post=1016170"},{"taxonomy":"movieyears","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieyears?post=1016170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}