{"id":1003427,"date":"2026-01-09T04:26:25","date_gmt":"2026-01-09T04:26:25","guid":{"rendered":"https:\/\/pandanetwork.club\/empirescenes\/2026\/01\/09\/deutsche-nachbarn-5\/"},"modified":"2026-01-09T04:26:25","modified_gmt":"2026-01-09T04:26:25","slug":"deutsche-nachbarn-5","status":"publish","type":"post","link":"https:\/\/pandanetwork.club\/empirescenes\/2026\/01\/09\/deutsche-nachbarn-5\/","title":{"rendered":"Deutsche Nachbarn 5"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2335],"tags":[],"movieactors":[7684,15469,2636,3297,7286,7480,9964,12442,21195],"moviegenres":[2389,2424,2512,2338,2495,2533,2340,2341,2828,2764,2349,2344,2513,2514],"moviestudios":[2826],"movieyears":[2820],"class_list":["post-1003427","post","type-post","status-publish","format-standard","hentry","category-adultempire-all-movies","movieactors-birgit","movieactors-kerstin","movieactors-martin","movieactors-martina","movieactors-oliver","movieactors-stefan","movieactors-stephan","movieactors-ute","movieactors-vivia","moviegenres-appearance","moviegenres-big-tits","moviegenres-blowjobs","moviegenres-couples","moviegenres-cumshots","moviegenres-cunnilingus","moviegenres-ethnic","moviegenres-european","moviegenres-german-language","moviegenres-germany","moviegenres-gonzo","moviegenres-international","moviegenres-language","moviegenres-oral","moviestudios-mmv","movieyears-2820"],"acf":[],"_links":{"self":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/1003427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/comments?post=1003427"}],"version-history":[{"count":0,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/posts\/1003427\/revisions"}],"wp:attachment":[{"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/media?parent=1003427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/categories?post=1003427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/tags?post=1003427"},{"taxonomy":"movieactors","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieactors?post=1003427"},{"taxonomy":"moviegenres","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviegenres?post=1003427"},{"taxonomy":"moviestudios","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/moviestudios?post=1003427"},{"taxonomy":"movieyears","embeddable":true,"href":"https:\/\/pandanetwork.club\/empirescenes\/wp-json\/wp\/v2\/movieyears?post=1003427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}